{"id":32711,"date":"2026-05-11T09:18:00","date_gmt":"2026-05-11T07:18:00","guid":{"rendered":"https:\/\/impactup.com\/poste\/key-account-manager-11\/"},"modified":"2026-05-13T01:00:05","modified_gmt":"2026-05-12T23:00:05","slug":"key-account-manager-11","status":"publish","type":"job_listing","link":"https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/","title":{"rendered":"Key Account Manager"},"content":{"rendered":"<p><strong>Entreprise<\/strong><\/p>\n<p>Entreprise fran\u00e7aise innovante cr\u00e9\u00e9e en 2021 nous sommes un acteur pionnier dans l\u2019\u00e9conomie circulaire appliqu\u00e9e aux piles alcalines.<\/p>\n<p style=\"text-align:justify\">Convaincu que performance \u00e9conomique et impact environnemental sont indissociables, nous d\u00e9veloppons une technologie unique permettant de r\u00e9g\u00e9n\u00e9rer des piles \u00e0 usage unique, \u00e9vitant ainsi leur enfouissement ou leur incin\u00e9ration pr\u00e9matur\u00e9e.<\/p>\n<p style=\"text-align:justify\">En proposant \u00e0 la fois des solutions destin\u00e9es au grand public et des \u00e9quipements connect\u00e9s pour les entreprises, nous r\u00e9pondons \u00e0 un double enjeu strat\u00e9gique : g\u00e9n\u00e9rer des \u00e9conomies mesurables tout en r\u00e9duisant significativement l\u2019empreinte environnementale.<\/p>\n<p style=\"text-align:justify\">Notre proposition de valeur s\u2019inscrit pleinement dans une d\u00e9marche RSE concr\u00e8te, tra\u00e7able et imm\u00e9diatement activable, en contribuant \u00e0 la r\u00e9duction des d\u00e9chets et \u00e0 l\u2019optimisation des ressources.<\/p>\n<p style=\"text-align:justify\">Port\u00e9e par une fabrication 100 % fran\u00e7aise et un mod\u00e8le align\u00e9 avec les enjeux de transition \u00e9cologique, nous connaissons aujourd\u2019hui une forte dynamique de croissance et une acc\u00e9l\u00e9ration de notre d\u00e9veloppement commercial.<\/p>\n<p style=\"text-align:justify\">Dans ce contexte de d\u00e9veloppement, nous recrutons<\/p>\n<p style=\"text-align:center\"><strong>Un(e) Key Account Manager<\/strong><\/p>\n<p><strong>Vos missions<\/strong><\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 G\u00e9rer et d\u00e9velopper un portefeuille de clients grands comptes strat\u00e9giques (activit\u00e9 BtoB)<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Assurer les n\u00e9gociations et r\u00e9f\u00e9rencements en centrale d\u2019achat\u00a0r\u00e9gionales et nationales des enseignes de distribution GSA et GSS (activit\u00e9 BtoBtoC)<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Prospecter et convertir de nouveaux comptes<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Identifier et activer de nouveaux canaux de distribution\u00a0: partenariats institutionnels, r\u00e9seaux d\u2019entreprises, plateformes RSE, collectivit\u00e9s territoriales<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Participer aux salons<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Assurer la mise en place et la formation des produits<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Contribuer \u00e0 la construction de l\u2019offre commerciale GD (conditions tarifaires, PLV, supports sell-in\/sell-out) en lien avec le Growth Manager<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Remonter les informations terrain (concurrence, rotations, opportunit\u00e9s) et assurer un reporting r\u00e9gulier \u00e0 la direction.<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Assurer une veille concurrentielle active sur le march\u00e9.<\/p>\n<p><strong>Vous \u00eates <\/strong><\/p>\n<p>De formation commerciale Bac&#43;5 (ou inf\u00e9rieure si exp\u00e9rience significative), vous justifiez d\u2019une exp\u00e9rience commerciale significative aupr\u00e8s de grands comptes et vous connaissez la grande distribution.<\/p>\n<p>Rompu(e) \u00e0 la n\u00e9gociation aupr\u00e8s d\u2019interlocuteurs C-level, vous avez une forte culture du d\u00e9veloppement et de la conqu\u00eate.<\/p>\n<p>Vous savez piloter vos comptes avec m\u00e9thode et sens du r\u00e9sultat.<\/p>\n<p>Vous avez un r\u00e9el int\u00e9r\u00eat pour l\u2019univers de l\u2019intelligence artificielle et \u00eates curieux(se) d\u2019explorer ses usages dans le d\u00e9veloppement commercial et la prospection.<\/p>\n<p>Vous \u00eates autonome, organis\u00e9(e), et savez g\u00e9rer les priorit\u00e9s<\/p>\n<p>Vous aimez travailler en \u00e9quipe, en esprit startup et contribuer \u00e0 une dynamique collective.<\/p>\n<p>Engag\u00e9(e), positif(ve), vous \u00eates concern\u00e9(e) par la transition \u00e9cologique et l\u2019\u00e9conomie circulaire et vous \u00eates convaincu(e) qu\u2019un commerce responsable a du sens.<\/p>\n<p style=\"text-align:justify\">Poste bas\u00e9 \u00e0 Paris d\u00e9placements \u00e0 pr\u00e9voir.<\/p>\n<p style=\"text-align:justify\">Envie de contribuer au d\u00e9veloppement d\u2019une entreprise engag\u00e9e et de piloter des projets \u00e0 fort impact ?<\/p>\n<p style=\"text-align:center\"><strong>Postulez d\u00e8s maintenant !<\/strong><\/p>\n<p><strong>Nos atouts <\/strong><\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Un projet \u00e0 fort impact environnemental et soci\u00e9tal, avec une technologie unique et brevet\u00e9e, fabrication 100\u00a0% fran\u00e7aise<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Un r\u00f4le cl\u00e9 et transverse au c\u0153ur de la phase d\u2019acc\u00e9l\u00e9ration de notre activit\u00e9 avec une vraie autonomie et un r\u00e9el pouvoir d\u2019action<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 R\u00e9mun\u00e9ration attractive\u00a0: fixe &#43; variable sur objectifs<\/p>\n<p>\u2022\u00a0\u00a0\u00a0\u00a0 Un environnement startup agile et bienveillant, port\u00e9 par une \u00e9quipe engag\u00e9e et passionn\u00e9e<\/p>\n<p>Recrutement confi\u00e9 au cabinet Impactup sp\u00e9cialis\u00e9 sur les fonctions commerciales et marketing <\/p>\n<p>Confidentialit\u00e9 assur\u00e9e <\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_promoted":"","_job_location":"75000 Paris, \u00cele-de-France","_application":"https:\/\/app.beetween.com\/WeaselWeb\/p\/#\/apply\/job\/q2u36vw5iq5k\/key-account-manager","_company_name":"","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-categories":[],"job-types":[37],"class_list":{"0":"post-32711","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"hentry","6":"job-type-cdi"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Key Account Manager - ImpactUp<\/title>\n<meta name=\"description\" content=\"Plus d&#039;informations sur Key Account Manager - Offres d&#039;emploi et de recrutement dans les fonctions commerciales et marketing\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Key Account Manager - ImpactUp\" \/>\n<meta property=\"og:description\" content=\"Plus d&#039;informations sur Key Account Manager - Offres d&#039;emploi et de recrutement dans les fonctions commerciales et marketing\" \/>\n<meta property=\"og:url\" content=\"https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/\" \/>\n<meta property=\"og:site_name\" content=\"ImpactUp\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T23:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/impactup.com\/wp-content\/uploads\/2021\/01\/og.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/impactup.com\\\/en\\\/poste\\\/key-account-manager-11\\\/\",\"url\":\"https:\\\/\\\/impactup.com\\\/en\\\/poste\\\/key-account-manager-11\\\/\",\"name\":\"Key Account Manager - ImpactUp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/impactup.com\\\/en\\\/#website\"},\"datePublished\":\"2026-05-11T07:18:00+00:00\",\"dateModified\":\"2026-05-12T23:00:05+00:00\",\"description\":\"Plus d'informations sur Key Account Manager - Offres d'emploi et de recrutement dans les fonctions commerciales et marketing\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/impactup.com\\\/en\\\/poste\\\/key-account-manager-11\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/impactup.com\\\/en\\\/poste\\\/key-account-manager-11\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/impactup.com\\\/en\\\/poste\\\/key-account-manager-11\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/impactup.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Key Account Manager\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/impactup.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/impactup.com\\\/en\\\/\",\"name\":\"ImpactUp\",\"description\":\"Recrutement commerciaux, directions commerciales et fonctions marketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/impactup.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Key Account Manager - ImpactUp","description":"Plus d'informations sur Key Account Manager - Offres d'emploi et de recrutement dans les fonctions commerciales et marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/","og_locale":"en_US","og_type":"article","og_title":"Key Account Manager - ImpactUp","og_description":"Plus d'informations sur Key Account Manager - Offres d'emploi et de recrutement dans les fonctions commerciales et marketing","og_url":"https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/","og_site_name":"ImpactUp","article_modified_time":"2026-05-12T23:00:05+00:00","og_image":[{"width":1067,"height":600,"url":"https:\/\/impactup.com\/wp-content\/uploads\/2021\/01\/og.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/","url":"https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/","name":"Key Account Manager - ImpactUp","isPartOf":{"@id":"https:\/\/impactup.com\/en\/#website"},"datePublished":"2026-05-11T07:18:00+00:00","dateModified":"2026-05-12T23:00:05+00:00","description":"Plus d'informations sur Key Account Manager - Offres d'emploi et de recrutement dans les fonctions commerciales et marketing","breadcrumb":{"@id":"https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/impactup.com\/en\/poste\/key-account-manager-11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/impactup.com\/en\/"},{"@type":"ListItem","position":2,"name":"Key Account Manager"}]},{"@type":"WebSite","@id":"https:\/\/impactup.com\/en\/#website","url":"https:\/\/impactup.com\/en\/","name":"ImpactUp","description":"Recrutement commerciaux, directions commerciales et fonctions marketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/impactup.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/impactup.com\/en\/wp-json\/wp\/v2\/job-listings\/32711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/impactup.com\/en\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/impactup.com\/en\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/impactup.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/impactup.com\/en\/wp-json\/wp\/v2\/media?parent=32711"}],"wp:term":[{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/impactup.com\/en\/wp-json\/wp\/v2\/job-categories?post=32711"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/impactup.com\/en\/wp-json\/wp\/v2\/job-types?post=32711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}